{"id":211,"count":15,"description":"","link":"http:\/\/www.prowin-tools.com\/es\/product-category\/dust-extractor-electric-sander\/","name":"Extractor de polvo y lijadora el\u00e9ctrica","slug":"dust-extractor-electric-sander","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":44,"_links":{"self":[{"href":"http:\/\/www.prowin-tools.com\/es\/wp-json\/wp\/v2\/product_cat\/211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.prowin-tools.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"http:\/\/www.prowin-tools.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"http:\/\/www.prowin-tools.com\/es\/wp-json\/wp\/v2\/product?product_cat=211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}